{"id":10338,"date":"2025-11-11T15:17:09","date_gmt":"2025-11-11T13:17:09","guid":{"rendered":"https:\/\/panmilar.ch\/event\/preparation-a-la-naissance-09-06-26-au-07-07-26\/"},"modified":"2025-11-11T15:17:43","modified_gmt":"2025-11-11T13:17:43","slug":"preparation-a-la-naissance-09-06-26-au-07-07-26","status":"publish","type":"tribe_events","link":"https:\/\/panmilar.ch\/tr\/event\/preparation-a-la-naissance-09-06-26-au-07-07-26\/","title":{"rendered":"Pr\u00e9paration \u00e0 la naissance \u2013 09.06.26 au 07.07.26"},"content":{"rendered":"<p>Mardi 9 juin 18h30-21h<br \/>\nMardi 16 juin 18h30-21h<br \/>\nMardi 23 juin 18h30-21h<br \/>\nMardi 30 juin 18h30-21h<br \/>\nMardi 7 juillet 18h30-21h<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mardi 9 juin 18h30-21h Mardi 16 juin 18h30-21h Mardi 23 juin 18h30-21h Mardi 30 juin 18h30-21h Mardi 7 juillet 18h30-21h<\/p>\n","protected":false},"author":4,"featured_media":8521,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[8],"class_list":["post-10338","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-lausanne","cat_lausanne"],"_links":{"self":[{"href":"https:\/\/panmilar.ch\/tr\/wp-json\/wp\/v2\/tribe_events\/10338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/panmilar.ch\/tr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/panmilar.ch\/tr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/panmilar.ch\/tr\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/panmilar.ch\/tr\/wp-json\/wp\/v2\/tribe_events\/10338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/panmilar.ch\/tr\/wp-json\/wp\/v2\/media\/8521"}],"wp:attachment":[{"href":"https:\/\/panmilar.ch\/tr\/wp-json\/wp\/v2\/media?parent=10338"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/panmilar.ch\/tr\/wp-json\/wp\/v2\/tags?post=10338"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/panmilar.ch\/tr\/wp-json\/wp\/v2\/tribe_events_cat?post=10338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}